{"id":10436,"date":"2024-10-14T16:46:40","date_gmt":"2024-10-14T14:46:40","guid":{"rendered":"https:\/\/hoteluzamecku.cz\/zauberhafter-herbst-im-hotel-chateau-cihelny-rabatte-bis-zu-30\/"},"modified":"2025-05-27T13:56:13","modified_gmt":"2025-05-27T11:56:13","slug":"zauberhafter-herbst-im-hotel-chateau-cihelny-rabatte-bis-zu-30","status":"publish","type":"post","link":"https:\/\/hoteluzamecku.cz\/de\/zauberhafter-herbst-im-hotel-chateau-cihelny-rabatte-bis-zu-30\/","title":{"rendered":"Zauberhafter Herbst im Hotel Ch\u00e2teau Cihelny Rabatte bis zu 30%"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Der perfekte Ort zur Entspannung!<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">Entspannen Sie sich in unserem Wellnessbereich und genie\u00dfen Sie die Herbsttage in ungest\u00f6rter Ruhe. <br\/>Wundersch\u00f6ne Natur, Entspannung und sportliche Aktivit\u00e4ten, all das und noch viel mehr erwartet Sie bereits. <br\/>Entdecken Sie die Karlovy Vary Region und ihr Naturjuwel wie den Slavkovsk\u00fd les, die Svato\u0161sk\u00e9 Felsen, die Kurstadt Karlovy Vary, das Schloss Be\u010dov nad Teplou oder die Burg Loket.<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Buchen Sie Ihren Aufenthalt \u00fcber die Online-Reservierung <\/strong> unter mit den Promo-Codes f\u00fcr \u00dcbernachtungen im Hotelkomplex Chateau Cihelny.<\/p>\n\n<p class=\"wp-block-paragraph\">1 Nacht 10&nbsp;% Rabatt mit dem Code PODZIM10<br\/>2 N\u00e4chte 15&nbsp;% Rabatt mit dem Code PODZIM15<br\/>5 N\u00e4chte 25&nbsp;% Rabatt mit dem Code PODZIM25<br\/>3 N\u00e4chte 20&nbsp;% Rabatt mit dem Code PODZIM20<br\/>7 N\u00e4chte 30&nbsp;% Rabatt mit dem Code PODZIM30<\/p>\n\n<p class=\"wp-block-paragraph\">Der Rabatt gilt f\u00fcr alle Geb\u00e4ude des Ch\u00e2teau-Hotelkomplexes. Wenden Sie den ausgew\u00e4hlten Rabatt hier an: <a href=\"https:\/\/chateaucihelny.cz\/de\/reservierung-chateau-cihelny\/\" target=\"_blank\" rel=\"noopener\">Z\u00e1me\u010dek<\/a>, <a href=\"https:\/\/hoteluzamecku.cz\/de\/reservierung-hotel\/\" data-type=\"link\" data-id=\"https:\/\/hoteluzamecku.cz\/rezervace-hotel\/\">Hotel<\/a>, <a href=\"https:\/\/chateaucihelny.cz\/de\/reservierung-villa\/\" target=\"_blank\" rel=\"noopener\">Villa<\/a>, <a href=\"https:\/\/chateaucihelny.cz\/de\/reservierung-pension\/\" target=\"_blank\" rel=\"noopener\">Pension<\/a>. <\/p>\n\n<p class=\"wp-block-paragraph\">Laden Sie hier den Flyer <a href=\"https:\/\/chateaucihelny.cz\/wp-content\/uploads\/2024\/10\/Chateau-Cihelny-Herbstentspannung.pdf\" target=\"_blank\" rel=\"noopener\">herunter<\/a>.<\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der perfekte Ort zur Entspannung! Entspannen Sie sich in unserem Wellnessbereich und genie\u00dfen Sie die Herbsttage in ungest\u00f6rter Ruhe. Wundersch\u00f6ne Natur, Entspannung und sportliche Aktivit\u00e4ten, all das und noch viel mehr erwartet Sie bereits. Entdecken Sie die Karlovy Vary Region und ihr Naturjuwel wie den Slavkovsk\u00fd les, die Svato\u0161sk\u00e9 Felsen, die Kurstadt Karlovy Vary, das [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":10431,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"iawp_total_views":7,"footnotes":""},"categories":[46,49,73,48],"tags":[],"class_list":["post-10436","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chateau-de","category-hotel-de","category-pension-de","category-villa-de"],"_links":{"self":[{"href":"https:\/\/hoteluzamecku.cz\/de\/wp-json\/wp\/v2\/posts\/10436","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hoteluzamecku.cz\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hoteluzamecku.cz\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hoteluzamecku.cz\/de\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/hoteluzamecku.cz\/de\/wp-json\/wp\/v2\/comments?post=10436"}],"version-history":[{"count":3,"href":"https:\/\/hoteluzamecku.cz\/de\/wp-json\/wp\/v2\/posts\/10436\/revisions"}],"predecessor-version":[{"id":10444,"href":"https:\/\/hoteluzamecku.cz\/de\/wp-json\/wp\/v2\/posts\/10436\/revisions\/10444"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hoteluzamecku.cz\/de\/wp-json\/wp\/v2\/media\/10431"}],"wp:attachment":[{"href":"https:\/\/hoteluzamecku.cz\/de\/wp-json\/wp\/v2\/media?parent=10436"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hoteluzamecku.cz\/de\/wp-json\/wp\/v2\/categories?post=10436"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hoteluzamecku.cz\/de\/wp-json\/wp\/v2\/tags?post=10436"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}